{"id":69459,"date":"2025-06-17T10:49:45","date_gmt":"2025-06-17T08:49:45","guid":{"rendered":"https:\/\/www.he-arc.ch\/?post_type=he-arc_event&#038;p=69459"},"modified":"2025-07-15T17:05:24","modified_gmt":"2025-07-15T15:05:24","slug":"action-et-resilience-pour-et-avec-les-personnes-lgbtiq","status":"publish","type":"he-arc_event","link":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/","title":{"rendered":"Action et r\u00e9silience pour et avec les personnes LGBTIQ"},"content":{"rendered":"\n<p><br>Cette apr\u00e8s-midi de conf\u00e9rences organis\u00e9e par l&#8217;<a href=\"https:\/\/www.he-arc.ch\/gestion-en\/institut-de-lutte-contre-la-criminalite-economique-ilce\/\" target=\"_blank\" rel=\"noreferrer noopener\">Institut de lutte contre la criminalit\u00e9 \u00e9conomique (ILCE)<\/a>, le Service Egalit\u00e9 de la HE-Arc, en partenariat avec la Ville de Neuch\u00e2tel, l<a href=\"https:\/\/www.ne.ch\/autorites\/DECS\/OPFE\/Pages\/accueil.aspx\">\u2019Office de Politique Familiale et de l\u2019Egalit\u00e9 du canton de Neuch\u00e2tel<\/a> et le <a href=\"https:\/\/www.unine.ch\/egalite\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bureau Egalit\u00e9 et Diversit\u00e9 de l\u2019Universit\u00e9 de Neuch\u00e2tel<\/a>, permettra d&#8217;explorer les d\u00e9fis et les r\u00e9alit\u00e9s v\u00e9cus par les personnes travaillant au plus proche des personnes LGBTIQ. <\/p>\n\n\n\n<p>A travers des courtes conf\u00e9rences de repr\u00e9sentant\u00b7e\u00b7s des milieux acad\u00e9mique et pratique, ainsi que des moments d&#8217;\u00e9changes, les intervenant\u00b7e\u00b7s auront l&#8217;occasion de partager des \u00e9tudes et des exp\u00e9riences sur les discriminations et abus v\u00e9cus par les populations LGBTIQ et de r\u00e9fl\u00e9chir \u00e0 des pistes d&#8217;actions et des strat\u00e9gies pour apporter un meilleur soutien face \u00e0 ces comportements.<\/p>\n\n\n\n<p>Public cible : <br>L&#8217;\u00e9v\u00e9nement s&#8217;adresse en particulier aux personnes travaillant sur les questions LGBTIQ, que ce soit au niveau institutionnel ou associatif, mais aussi aux personnes int\u00e9ress\u00e9es plus largement par ce sujet.<\/p>\n\n\n\n<p>HEG &#8211; Haute \u00e9cole de gestion Arc<br>Espace de l\u2019Europe 21<br>2000 Neuch\u00e2tel<br>Auditorium 2 (salle 030, rez-de-chauss\u00e9e)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2025\/07\/GES-FLY250828-Conference-LGBTIQ.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Programme<\/a><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/jp-portal.gestion.he-arc.ch\/apex\/f?p=444:50:::::P50_NUMERO:174\">Inscription<\/a><\/li>\n<\/ul>\n","protected":false},"author":12,"featured_media":70452,"template":"","he-arc_domain":[2],"he-arc_event_category":[16],"class_list":["post-69459","he-arc_event","type-he-arc_event","status-publish","has-post-thumbnail","hentry","he-arc_domain-gestion","he-arc_event_category-seminaire-conference"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Action et r\u00e9silience pour et avec les personnes LGBTIQ - Haute-Ecole Arc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Action et r\u00e9silience pour et avec les personnes LGBTIQ - Haute-Ecole Arc\" \/>\n<meta property=\"og:description\" content=\"Cette apr\u00e8s-midi de conf\u00e9rences organis\u00e9e par l&#8217;Institut de lutte contre la criminalit\u00e9 \u00e9conomique (ILCE), le Service Egalit\u00e9 de la HE-Arc, en partenariat avec la Ville de Neuch\u00e2tel, l\u2019Office de Politique Familiale et de l\u2019Egalit\u00e9 du canton de Neuch\u00e2tel et le Bureau Egalit\u00e9 et Diversit\u00e9 de l\u2019Universit\u00e9 de Neuch\u00e2tel, permettra d&#8217;explorer les d\u00e9fis et les r\u00e9alit\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/\" \/>\n<meta property=\"og:site_name\" content=\"Haute-Ecole Arc\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-15T15:05:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2025\/07\/Illustrattion-brochure.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1190\" \/>\n\t<meta property=\"og:image:height\" content=\"789\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/\",\"url\":\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/\",\"name\":\"Action et r\u00e9silience pour et avec les personnes LGBTIQ - Haute-Ecole Arc\",\"isPartOf\":{\"@id\":\"https:\/\/www.he-arc.ch\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2025\/07\/Illustrattion-brochure.png\",\"datePublished\":\"2025-06-17T08:49:45+00:00\",\"dateModified\":\"2025-07-15T15:05:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#primaryimage\",\"url\":\"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2025\/07\/Illustrattion-brochure.png\",\"contentUrl\":\"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2025\/07\/Illustrattion-brochure.png\",\"width\":1190,\"height\":789,\"caption\":\"Visuel conf\u00e9rence \\\"Action et r\u00e9silience avec et pour les personnes LGBTIQ\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.he-arc.ch\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/www.he-arc.ch\/en\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Action et r\u00e9silience pour et avec les personnes LGBTIQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.he-arc.ch\/en\/#website\",\"url\":\"https:\/\/www.he-arc.ch\/en\/\",\"name\":\"Haute-Ecole Arc\",\"description\":\"Haute \u00e9cole sp\u00e9cialis\u00e9e Suisse. Gestion, Ing\u00e9nierie, Sant\u00e9, Conservation-\u200brestauration.\",\"publisher\":{\"@id\":\"https:\/\/www.he-arc.ch\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.he-arc.ch\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.he-arc.ch\/en\/#organization\",\"name\":\"Haute Ecole Arc\",\"url\":\"https:\/\/www.he-arc.ch\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.he-arc.ch\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2022\/01\/logo-he-arc.svg\",\"contentUrl\":\"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2022\/01\/logo-he-arc.svg\",\"width\":140,\"height\":42,\"caption\":\"Haute Ecole Arc\"},\"image\":{\"@id\":\"https:\/\/www.he-arc.ch\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Action et r\u00e9silience pour et avec les personnes LGBTIQ - Haute-Ecole Arc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/","og_locale":"en_US","og_type":"article","og_title":"Action et r\u00e9silience pour et avec les personnes LGBTIQ - Haute-Ecole Arc","og_description":"Cette apr\u00e8s-midi de conf\u00e9rences organis\u00e9e par l&#8217;Institut de lutte contre la criminalit\u00e9 \u00e9conomique (ILCE), le Service Egalit\u00e9 de la HE-Arc, en partenariat avec la Ville de Neuch\u00e2tel, l\u2019Office de Politique Familiale et de l\u2019Egalit\u00e9 du canton de Neuch\u00e2tel et le Bureau Egalit\u00e9 et Diversit\u00e9 de l\u2019Universit\u00e9 de Neuch\u00e2tel, permettra d&#8217;explorer les d\u00e9fis et les r\u00e9alit\u00e9s [&hellip;]","og_url":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/","og_site_name":"Haute-Ecole Arc","article_modified_time":"2025-07-15T15:05:24+00:00","og_image":[{"width":1190,"height":789,"url":"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2025\/07\/Illustrattion-brochure.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/","url":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/","name":"Action et r\u00e9silience pour et avec les personnes LGBTIQ - Haute-Ecole Arc","isPartOf":{"@id":"https:\/\/www.he-arc.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#primaryimage"},"image":{"@id":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#primaryimage"},"thumbnailUrl":"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2025\/07\/Illustrattion-brochure.png","datePublished":"2025-06-17T08:49:45+00:00","dateModified":"2025-07-15T15:05:24+00:00","breadcrumb":{"@id":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#primaryimage","url":"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2025\/07\/Illustrattion-brochure.png","contentUrl":"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2025\/07\/Illustrattion-brochure.png","width":1190,"height":789,"caption":"Visuel conf\u00e9rence \"Action et r\u00e9silience avec et pour les personnes LGBTIQ\""},{"@type":"BreadcrumbList","@id":"https:\/\/www.he-arc.ch\/en\/agenda\/action-et-resilience-pour-et-avec-les-personnes-lgbtiq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.he-arc.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.he-arc.ch\/en\/events\/"},{"@type":"ListItem","position":3,"name":"Action et r\u00e9silience pour et avec les personnes LGBTIQ"}]},{"@type":"WebSite","@id":"https:\/\/www.he-arc.ch\/en\/#website","url":"https:\/\/www.he-arc.ch\/en\/","name":"Haute-Ecole Arc","description":"Haute \u00e9cole sp\u00e9cialis\u00e9e Suisse. Gestion, Ing\u00e9nierie, Sant\u00e9, Conservation-\u200brestauration.","publisher":{"@id":"https:\/\/www.he-arc.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.he-arc.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.he-arc.ch\/en\/#organization","name":"Haute Ecole Arc","url":"https:\/\/www.he-arc.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.he-arc.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2022\/01\/logo-he-arc.svg","contentUrl":"https:\/\/www.he-arc.ch\/wp-content\/uploads\/2022\/01\/logo-he-arc.svg","width":140,"height":42,"caption":"Haute Ecole Arc"},"image":{"@id":"https:\/\/www.he-arc.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/he-arc_event\/69459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/he-arc_event"}],"about":[{"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/types\/he-arc_event"}],"author":[{"embeddable":true,"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/users\/12"}],"version-history":[{"count":4,"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/he-arc_event\/69459\/revisions"}],"predecessor-version":[{"id":70380,"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/he-arc_event\/69459\/revisions\/70380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/media\/70452"}],"wp:attachment":[{"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/media?parent=69459"}],"wp:term":[{"taxonomy":"he-arc_domain","embeddable":true,"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/he-arc_domain?post=69459"},{"taxonomy":"he-arc_event_category","embeddable":true,"href":"https:\/\/www.he-arc.ch\/en\/wp-json\/wp\/v2\/he-arc_event_category?post=69459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}